{"id":369,"date":"2023-04-30T17:52:08","date_gmt":"2023-04-30T15:52:08","guid":{"rendered":"https:\/\/eve95ermont.com\/?page_id=369"},"modified":"2025-09-07T07:59:58","modified_gmt":"2025-09-07T05:59:58","slug":"accueil-ermont-ville-europe-2","status":"publish","type":"page","link":"https:\/\/eve95ermont.com\/","title":{"rendered":"Accueil"},"content":{"rendered":"\n<!-- Ce style est la pour enlever la pagination pour les articles qui n'est pas fonctionnel sur la page d'accueil -->\n<style>\n\n  .post-grid .pagination {\n    display: none !important;\n  }\n<\/style>\n\n\n<div data-post-id=\"45\" class=\"insert-page insert-page-45 \">\n\n\n<h2 class=\"wp-block-heading\">Actualit\u00e9s<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ci-dessous vous trouverez la liste des points d&rsquo;actualit\u00e9 de notre association (\u00e9v\u00e9nements, articles, etc&#8230;)<\/p>\n\n\n            <div id=\"post-grid-lazy-224\" class=\"post-grid-lazy\"><img decoding=\"async\" alt=\"\" src=\"\" \/><\/div>\n        <script>\n            jQuery('#post-grid-lazy-224').ready(function($) {\n                $('#post-grid-lazy-224').fadeOut();\n                $('#post-grid-224   ').fadeIn();\n            })\n        <\/script>\n        <style type=\"text\/css\">\n            #post-grid-224 {\n                display: none;\n            }\n\n            .post-grid-lazy {\n                text-align: center;\n            }\n        <\/style>\n        <div data-options='{&quot;id&quot;:&quot;224&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;masonry_enable&quot;:&quot;no&quot;,&quot;view_type&quot;:&quot;grid&quot;}' id=\"post-grid-224\" class=\"post-grid grid\">\n                <div class=\"grid-items\">\n            <div class=\"item item-1523 skin flat even 0 \">\n                <div class=\"layer-wrapper layout-127\">\n                <a class=\" element_1682835123535\" id=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2026\/04\/26\/sejour-jumelage-ermont-loja-swidnica-2026\/\">\n\n\n        <div class=\"element element_1682834639594  thumb_link \">\n                    <img decoding=\"async\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026-1024x576.png\">\n        \n\n    <\/div>\n    <div class=\"element element_1682244529733  title \">\n                    <a target=\"_blank\" href=\"https:\/\/eve95ermont.com\/index.php\/2026\/04\/26\/sejour-jumelage-ermont-loja-swidnica-2026\/\">S\u00e9jour Jumelage \u00e0 Ermont : Accueil de Loja et \u015awidnica | E.V.E du 8 au 13 Avril 2026<\/a>\n\n        \n\n    <\/div>\n    <hr class=\"element element_1682832568808  hr \">\n    <\/hr>\n    <div class=\"element element_1689186392009  excerpt \">\n        Revivez les temps forts du s\u00e9jour organis\u00e9 par l&rsquo;association E.V.E du 8 au 13 avril 2026. Entre r\u00e9ceptions officielles pour les 25 ans de jumelage, visites culturelles au S\u00e9nat et \u00e0 Notre-Dame, et ateliers cuisine conviviaux, Ermont a vibr\u00e9 au rythme de l&rsquo;amiti\u00e9 avec nos amis de Loja et \u015awidnica.            <\/div>\n    <\/a>\n        <\/div>\n    <\/div><div class=\"item item-1429 skin flat odd 1 \">\n                <div class=\"layer-wrapper layout-127\">\n                <a class=\" element_1682835123535\" id=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/10\/04\/flash-eve-magazine-ermont-2024-2025\/\">\n\n\n        <div class=\"element element_1682834639594  thumb_link \">\n                    <img decoding=\"async\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/10\/logo-flash-eve-v3.png\">\n        \n\n    <\/div>\n    <div class=\"element element_1682244529733  title \">\n                    <a target=\"_blank\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/10\/04\/flash-eve-magazine-ermont-2024-2025\/\">Flash Eve n\u00b01 \u2013 2024\/2025 : Le magazine de nos r\u00e9alisations et de nos projets \u00e0 venir<\/a>\n\n        \n\n    <\/div>\n    <hr class=\"element element_1682832568808  hr \">\n    <\/hr>\n    <div class=\"element element_1689186392009  excerpt \">\n                    <\/div>\n    <\/a>\n        <\/div>\n    <\/div><div class=\"item item-351 skin flat even 2 \">\n                <div class=\"layer-wrapper layout-127\">\n                <a class=\" element_1682835123535\" id=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2023\/04\/30\/chaine-youtube-eve-desormais-disponible\/\">\n\n\n        <div class=\"element element_1682834639594  thumb_link \">\n                    <img decoding=\"async\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2023\/05\/image-1024x495.png\">\n        \n\n    <\/div>\n    <div class=\"element element_1682244529733  title \">\n                    <a target=\"_blank\" href=\"https:\/\/eve95ermont.com\/index.php\/2023\/04\/30\/chaine-youtube-eve-desormais-disponible\/\">Chaine Youtube EVE d\u00e9sormais disponible !!<\/a>\n\n        \n\n    <\/div>\n    <hr class=\"element element_1682832568808  hr \">\n    <\/hr>\n    <div class=\"element element_1689186392009  excerpt \">\n        Notre cha\u00eene YouTube est cr\u00e9\u00e9e ! Elle est disponible \u00e0 l&rsquo;adresse : https:\/\/www.youtube.com\/@EVE_Ermont\/videos            <\/div>\n    <\/a>\n        <\/div>\n    <\/div>        <\/div>\n        <div class=\"pagination\">\n            <div class=\"paginate\">\n            <\/div>\n    <style type=\"text\/css\">\n        #post-grid-224 .pagination .page-numbers {\n            font-size: 16px;\n            color: #fff;\n            background: #646464;\n        }\n\n        #post-grid-224 .pagination .page-numbers:hover,\n        #post-grid-224 .pagination .page-numbers.current {\n            background: #4b4b4b;\n        }\n    <\/style>\n    <\/div>\n    <style type=\"text\/css\">\n        .layout-127 .element_1682834639594 {\n            overflow: hidden;\n                    }\n\n        .layout-127 .element_1682834639594 img {\n            max-width: 100%;\n            height: auto;\n        }\n\n        @media only screen and (min-width: 1024px) {\n            .layout-127 .element_1682834639594 {\n                            }\n        }\n\n        @media only screen and (min-width: 768px) and (max-width: 1023px) {\n            .layout-127 .element_1682834639594 {\n                            }\n        }\n\n        @media only screen and (min-width: 0px) and (max-width: 767px) {\n            .layout-127 .element_1682834639594 {\n                            }\n        }\n    <\/style>\n    <style type=\"text\/css\">\n        .layout-127 .element_1682244529733 {\n            color: #1e73be;\n            text-align: left;\n            font-weight:bold;\r\ntext-decoration: none;        }\n\n        .layout-127 .element_1682244529733 a {\n            color: #1e73be;\n            text-align: left;\n            font-weight:bold;\r\ntext-decoration: none;        }\n    <\/style>\n    <style type=\"text\/css\">\n        .layout-127 .element_1682832568808 {\n                    }\n\n            <\/style>\n    <style type=\"text\/css\">\n        .layout-127 .element_1689186392009 {\n            text-align: left;\n                    }\n\n        .layout-127 .element_1689186392009 a {\n                    }\n    <\/style>\n    \n\n        <script>\n        \n            <\/script>\n        <style type=\"text\/css\">\n        #post-grid-224 {\n                    }\n\n        #post-grid-224 .item {\n            \/*             margin:;\n         *\/\n            padding: 0px;\n            background: #fff;\n                    }\n\n        #post-grid-224 .item .layer-media {\n            height:auto;        }\n\n        @media only screen and (min-width: 0px) and (max-width: 767px) {\n            #post-grid-224 .grid-items {\n                display: grid;\n                grid-template-columns: 1fr ;\n                column-gap: 10px;\n                row-gap: 10px;\n                ;\n\n            }\n\n            #post-grid-224 .item {\n                height:auto;            }\n        }\n\n        @media only screen and (min-width: 768px) and (max-width: 1023px) {\n            #post-grid-224 .grid-items {\n                display: grid;\n                grid-template-columns: 1fr 1fr ;\n                column-gap: 10px;\n                row-gap: 10px             }\n\n            #post-grid-224 .item {\n                max-height:auto;            }\n        }\n\n        @media only screen and (min-width: 1024px) {\n            #post-grid-224 .grid-items {\n                display: grid;\n                grid-template-columns: 1fr 1fr 1fr ;\n                column-gap: 10px;\n                row-gap: 10px;\n                            }\n\n            #post-grid-224 .item {\n                height:auto;            }\n        }\n\n            <\/style>\n    <\/div>\n\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Articles<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez ci-dessous tous les articles mentionnant nos activit\u00e9s et les sp\u00e9cificit\u00e9s de chaque ville jumel\u00e9e<\/p>\n\n\n            <div id=\"post-grid-lazy-765\" class=\"post-grid-lazy\"><img decoding=\"async\" alt=\"\" src=\"\" \/><\/div>\n        <script>\n            jQuery('#post-grid-lazy-765').ready(function($) {\n                $('#post-grid-lazy-765').fadeOut();\n                $('#post-grid-765   ').fadeIn();\n            })\n        <\/script>\n        <style type=\"text\/css\">\n            #post-grid-765 {\n                display: none;\n            }\n\n            .post-grid-lazy {\n                text-align: center;\n            }\n        <\/style>\n        <div data-options='{&quot;id&quot;:&quot;765&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;masonry_enable&quot;:&quot;no&quot;,&quot;view_type&quot;:&quot;grid&quot;}' id=\"post-grid-765\" class=\"post-grid grid\">\n                <div class=\"grid-items\">\n            <div class=\"item item-1523 skin flat even 0 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2026\/04\/26\/sejour-jumelage-ermont-loja-swidnica-2026\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026-1024x576.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Loja et Swidnica \u00e0 Ermont 2026\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026-1024x576.png 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026-300x169.png 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026-768x432.png 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026-1536x864.png 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2026\/04\/loja-et-swidnica-a-ermont-2026.png 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2026\/04\/26\/sejour-jumelage-ermont-loja-swidnica-2026\/\">S\u00e9jour Jumelage \u00e0 Ermont : Accueil de Loja et \u015awidnica | E.V.E du 8 au 13 Avril 2026<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Revivez les temps forts du s\u00e9jour organis\u00e9 par l'association E.V.E du 8 au 13 avril 2026. Entre r\u00e9ceptions officielles pour            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2026\/04\/26\/sejour-jumelage-ermont-loja-swidnica-2026\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1481 skin flat odd 1 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/12\/22\/marche-de-noel-de-la-communaute-de-village-de-swidnica-pologne-annee-2025\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/12\/image-1-1024x768.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/12\/image-1-1024x768.png 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/12\/image-1-300x225.png 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/12\/image-1-768x576.png 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/12\/image-1-1536x1152.png 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/12\/image-1.png 2048w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/12\/22\/marche-de-noel-de-la-communaute-de-village-de-swidnica-pologne-annee-2025\/\">March\u00e9 de No\u00ebl de la communaut\u00e9 de village de \u015awidnica (Pologne) &#8211; Ann\u00e9e 2025<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Le march\u00e9 de No\u00ebl de \u015awidnica, organis\u00e9 par la communaut\u00e9 de villages et l\u2019association de la ville jumel\u00e9e, a rassembl\u00e9            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/12\/22\/marche-de-noel-de-la-communaute-de-village-de-swidnica-pologne-annee-2025\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1455 skin flat even 2 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/11\/29\/sejour-a-banbury\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/11\/IMG-20251107-WA0001-1024x768.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"S\u00e9jour \u00e0 Banbury\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/11\/IMG-20251107-WA0001-1024x768.jpg 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/11\/IMG-20251107-WA0001-300x225.jpg 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/11\/IMG-20251107-WA0001-768x576.jpg 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/11\/IMG-20251107-WA0001-1536x1152.jpg 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/11\/IMG-20251107-WA0001.jpg 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/11\/29\/sejour-a-banbury\/\">S\u00e9jour \u00e0 Banbury<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Du 2 au 6 octobre 2025, trois membres de notre association se sont rendus \u00e0 Banbury...            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/11\/29\/sejour-a-banbury\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1429 skin flat odd 3 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/10\/04\/flash-eve-magazine-ermont-2024-2025\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/10\/logo-flash-eve-v3.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Logo flash Eve\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/10\/logo-flash-eve-v3.png 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/10\/logo-flash-eve-v3-300x300.png 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/10\/logo-flash-eve-v3-150x150.png 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/10\/04\/flash-eve-magazine-ermont-2024-2025\/\">Flash Eve n\u00b01 \u2013 2024\/2025 : Le magazine de nos r\u00e9alisations et de nos projets \u00e0 venir<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Notre premier magazine des actions de l\u2019association est disponible ! \ud83c\udf89 Dans ce num\u00e9ro, vous d\u00e9couvrirez :            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/10\/04\/flash-eve-magazine-ermont-2024-2025\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1412 skin flat even 4 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/09\/07\/assemblee-generale-2025-stade-raoul-dautry\/\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/ag-2025-2-768x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/ag-2025-2-768x1024.jpg 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/ag-2025-2-225x300.jpg 225w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/ag-2025-2-1152x1536.jpg 1152w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/ag-2025-2.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/09\/07\/assemblee-generale-2025-stade-raoul-dautry\/\">Assembl\u00e9e G\u00e9n\u00e9rale 2025 &#8211; 21 Septembre 2025 &#8211; Stade Raoul Dautry<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Le 21 septembre 2025 avait lieu notre Assembl\u00e9e g\u00e9n\u00e9rale...            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/09\/07\/assemblee-generale-2025-stade-raoul-dautry\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1375 skin flat odd 5 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/09\/05\/sejour-swidnica-2025\/\"><img loading=\"lazy\" decoding=\"async\" width=\"541\" height=\"406\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/image-16.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/image-16.png 541w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/09\/image-16-300x225.png 300w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/09\/05\/sejour-swidnica-2025\/\">F\u00eates des moissons (do\u017cynki) 2025 \u00e0 \u015awidnica<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Retour sur notre s\u00e9jour \u00e0 \u015awidnica en 2025 : visites culturelles et F\u00eates des moissons v\u00e9cues au c\u0153ur des traditions.            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/09\/05\/sejour-swidnica-2025\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1289 skin flat even 6 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/07\/26\/fete-des-jumelages-lampertheim-du-27-au-29-juin-2025\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-06-30-a-15.00.21_0a838f6b-1024x768.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-06-30-a-15.00.21_0a838f6b-1024x768.jpg 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-06-30-a-15.00.21_0a838f6b-300x225.jpg 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-06-30-a-15.00.21_0a838f6b-768x576.jpg 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-06-30-a-15.00.21_0a838f6b-1536x1152.jpg 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-06-30-a-15.00.21_0a838f6b.jpg 2000w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/07\/26\/fete-des-jumelages-lampertheim-du-27-au-29-juin-2025\/\">F\u00eate des Jumelages &#8211; Lampertheim &#8211; du 27 au 29 Juin 2025<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Du 27 au 29 juin 2025, quelques membres d\u2019Ermont Ville d\u2019Europe ont particip\u00e9 \u00e0 la f\u00eate des jumelages* organis\u00e9e cette            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/07\/26\/fete-des-jumelages-lampertheim-du-27-au-29-juin-2025\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1293 skin flat odd 7 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/04\/01\/un-atelier-cuisine-aux-couleurs-de-leurope\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/04\/IMG-20250308-WA0029-1024x768.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Atelier cuisine du 8 mars\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/04\/IMG-20250308-WA0029-1024x768.jpg 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/04\/IMG-20250308-WA0029-300x225.jpg 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/04\/IMG-20250308-WA0029-768x576.jpg 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/04\/IMG-20250308-WA0029-1536x1152.jpg 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/04\/IMG-20250308-WA0029.jpg 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/04\/01\/un-atelier-cuisine-aux-couleurs-de-leurope\/\">UN ATELIER CUISINE\u00a0AUX COULEURS DE L\u2019EUROPE<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Le 8 mars avait lieu notre traditionnel atelier cuisine. Les saveurs de l'Europe \u00e9taient au rendez-vous.            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/04\/01\/un-atelier-cuisine-aux-couleurs-de-leurope\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1265 skin flat even 8 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/01\/03\/galettes-des-rois-28-janvier-2024-16h-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/01\/IMG_20250118_150007-768x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/01\/IMG_20250118_150007-768x1024.jpg 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/01\/IMG_20250118_150007-225x300.jpg 225w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/01\/IMG_20250118_150007-1152x1536.jpg 1152w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/01\/IMG_20250118_150007-1536x2048.jpg 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2025\/01\/IMG_20250118_150007-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/01\/03\/galettes-des-rois-28-janvier-2024-16h-2\/\">Des galettes et des rois<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Ermont Ville d'Europe - Galette des rois, le 18 Janvier 2025 \u00e0 la salle de l'Arche            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2025\/01\/03\/galettes-des-rois-28-janvier-2024-16h-2\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div><div class=\"item item-1190 skin flat odd 9 \">\n                <div class=\"layer-wrapper layout-\">\n                <div class=\"layer-media\"><\/div>\n    <div class=\"layer-content\">\n            <div class=\"element element_0  element-media \">\n        <a target=\"_self\" href=\"https:\/\/eve95ermont.com\/index.php\/2024\/12\/04\/excursion-a-loja\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2024\/12\/IMG-20241113-WA0014-1024x768.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/eve95ermont.com\/wp-content\/uploads\/2024\/12\/IMG-20241113-WA0014-1024x768.jpg 1024w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2024\/12\/IMG-20241113-WA0014-300x225.jpg 300w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2024\/12\/IMG-20241113-WA0014-768x576.jpg 768w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2024\/12\/IMG-20241113-WA0014-1536x1152.jpg 1536w, https:\/\/eve95ermont.com\/wp-content\/uploads\/2024\/12\/IMG-20241113-WA0014.jpg 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\n    <\/div>\n    <div class=\"element element_1  title_link \">\n                    <a target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2024\/12\/04\/excursion-a-loja\/\">Excursion \u00e0 Loja<\/a>\n            <\/div>\n    <div class=\"element element_2  excerpt \">\n        Excursion \u00e0 Loja Du 8 au 12 novembre 2024, les membres de l\u2019association Ermont Ville d\u2019Europe ont eu le plaisir            <\/div>\n            <a class=\"element element_3  read_more \" target=\"\" href=\"https:\/\/eve95ermont.com\/index.php\/2024\/12\/04\/excursion-a-loja\/\"><\/a>\n    \n    <\/div>\n        <\/div>\n    <\/div>        <\/div>\n        <div class=\"pagination\">\n            <div class=\"paginate\">\n        <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages\/369\/page\/2\/\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages\/369\/page\/3\/\">3<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages\/369\/page\/2\/\">Next \u00bb<\/a>    <\/div>\n    <style type=\"text\/css\">\n        #post-grid-765 .pagination .page-numbers {\n            font-size: 16px;\n            color: #fff;\n            background: #646464;\n        }\n\n        #post-grid-765 .pagination .page-numbers:hover,\n        #post-grid-765 .pagination .page-numbers.current {\n            background: #4b4b4b;\n        }\n    <\/style>\n    <\/div>\n    \n\n        <script>\n        \n            <\/script>\n        <style type=\"text\/css\">\n        #post-grid-765 .element_0 {\n            display: block;font-size: 21px;line-height: normal;padding: 5px 10px;text-align: left; text-decoration: none;        }\n\n        #post-grid-765 .element_1 {\n            display: block;font-size: 21px;line-height: normal;padding: 5px 10px;text-align: left; text-decoration: none;        }\n\n        #post-grid-765 .element_2 {\n            display: block;font-size: 14px;padding: 5px 10px;text-align: left;        }\n\n        #post-grid-765 .element_3 {\n            display: block;font-size: 12px;font-weight: bold;padding: 0 10px;text-align: left;text-decoration: none;        }\n\n        #post-grid-765 .element_0:hover{}#post-grid-765 .element_1:hover{}#post-grid-765 .element_2:hover{}#post-grid-765 .element_3:hover{}    <\/style>\n    <style type=\"text\/css\">\n        #post-grid-765 {\n                    }\n\n        #post-grid-765 .item {\n            \/*             margin:;\n         *\/\n            padding: 0px;\n            background: #fff;\n                    }\n\n        #post-grid-765 .item .layer-media {\n            height:auto;        }\n\n        @media only screen and (min-width: 0px) and (max-width: 767px) {\n            #post-grid-765 .grid-items {\n                display: grid;\n                grid-template-columns: 1fr ;\n                column-gap: 10px;\n                row-gap: 10px;\n                ;\n\n            }\n\n            #post-grid-765 .item {\n                height:auto;            }\n        }\n\n        @media only screen and (min-width: 768px) and (max-width: 1023px) {\n            #post-grid-765 .grid-items {\n                display: grid;\n                grid-template-columns: 1fr 1fr ;\n                column-gap: 10px;\n                row-gap: 10px             }\n\n            #post-grid-765 .item {\n                max-height:auto;            }\n        }\n\n        @media only screen and (min-width: 1024px) {\n            #post-grid-765 .grid-items {\n                display: grid;\n                grid-template-columns: 1fr 1fr 1fr ;\n                column-gap: 10px;\n                row-gap: 10px;\n                            }\n\n            #post-grid-765 .item {\n                height:auto;            }\n        }\n\n            <\/style>\n    <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Articles Vous trouverez ci-dessous tous les articles mentionnant nos activit\u00e9s et les sp\u00e9cificit\u00e9s de chaque ville jumel\u00e9e<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-369","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - Ermont Ville d&#039;Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eve95ermont.com\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - Ermont Ville d&#039;Europe\" \/>\n<meta property=\"og:description\" content=\"Articles Vous trouverez ci-dessous tous les articles mentionnant nos activit\u00e9s et les sp\u00e9cificit\u00e9s de chaque ville jumel\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eve95ermont.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Ermont Ville d&#039;Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-07T05:59:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/\",\"url\":\"https:\\\/\\\/eve95ermont.com\\\/\",\"name\":\"Accueil - Ermont Ville d&#039;Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#website\"},\"datePublished\":\"2023-04-30T15:52:08+00:00\",\"dateModified\":\"2025-09-07T05:59:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eve95ermont.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/eve95ermont.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#website\",\"url\":\"https:\\\/\\\/eve95ermont.com\\\/\",\"name\":\"Ermont Ville d&#039;Europe\",\"description\":\"L&#039;association de jumelage d&#039;Ermont\",\"publisher\":{\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eve95ermont.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#organization\",\"name\":\"Ermont Ville d&#039;Europe\",\"url\":\"https:\\\/\\\/eve95ermont.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eve95ermont.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-eve-proposition-gris-clair-contour-noir-v2.png\",\"contentUrl\":\"https:\\\/\\\/eve95ermont.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logo-eve-proposition-gris-clair-contour-noir-v2.png\",\"width\":1157,\"height\":709,\"caption\":\"Ermont Ville d&#039;Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/eve95ermont.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - Ermont Ville d&#039;Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eve95ermont.com\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - Ermont Ville d&#039;Europe","og_description":"Articles Vous trouverez ci-dessous tous les articles mentionnant nos activit\u00e9s et les sp\u00e9cificit\u00e9s de chaque ville jumel\u00e9e","og_url":"https:\/\/eve95ermont.com\/","og_site_name":"Ermont Ville d&#039;Europe","article_modified_time":"2025-09-07T05:59:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eve95ermont.com\/","url":"https:\/\/eve95ermont.com\/","name":"Accueil - Ermont Ville d&#039;Europe","isPartOf":{"@id":"https:\/\/eve95ermont.com\/#website"},"datePublished":"2023-04-30T15:52:08+00:00","dateModified":"2025-09-07T05:59:58+00:00","breadcrumb":{"@id":"https:\/\/eve95ermont.com\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eve95ermont.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eve95ermont.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/eve95ermont.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/eve95ermont.com\/#website","url":"https:\/\/eve95ermont.com\/","name":"Ermont Ville d&#039;Europe","description":"L&#039;association de jumelage d&#039;Ermont","publisher":{"@id":"https:\/\/eve95ermont.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eve95ermont.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eve95ermont.com\/#organization","name":"Ermont Ville d&#039;Europe","url":"https:\/\/eve95ermont.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eve95ermont.com\/#\/schema\/logo\/image\/","url":"https:\/\/eve95ermont.com\/wp-content\/uploads\/2023\/06\/cropped-logo-eve-proposition-gris-clair-contour-noir-v2.png","contentUrl":"https:\/\/eve95ermont.com\/wp-content\/uploads\/2023\/06\/cropped-logo-eve-proposition-gris-clair-contour-noir-v2.png","width":1157,"height":709,"caption":"Ermont Ville d&#039;Europe"},"image":{"@id":"https:\/\/eve95ermont.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":12,"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages\/369\/revisions"}],"predecessor-version":[{"id":1420,"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/pages\/369\/revisions\/1420"}],"wp:attachment":[{"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eve95ermont.com\/index.php\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}